{"id":18980,"date":"2014-10-24T07:42:55","date_gmt":"2014-10-24T06:42:55","guid":{"rendered":"http:\/\/www.bevershof.be\/nl\/?page_id=18980"},"modified":"2023-11-04T21:29:33","modified_gmt":"2023-11-04T20:29:33","slug":"afhaalgerechten","status":"publish","type":"page","link":"https:\/\/www.bevershof.be\/nl\/formules\/afhaalgerechten\/","title":{"rendered":"Afhaalgerechten"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row bg_type=&#8221;no_bg&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21741\" src=\"https:\/\/www.bevershof.be\/nl\/illustraties\/luchtfoto-bevershof.png\" alt=\"\" width=\"907\" height=\"557\" srcset=\"https:\/\/www.bevershof.be\/nl\/illustraties\/luchtfoto-bevershof.png 907w, https:\/\/www.bevershof.be\/nl\/illustraties\/luchtfoto-bevershof-300x184.png 300w\" sizes=\"auto, (max-width: 907px) 100vw, 907px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21740 alignnone\" src=\"https:\/\/www.bevershof.be\/nl\/illustraties\/underconstruction.gif\" alt=\"\" width=\"254\" height=\"193\" \/><\/p>\n<p>&nbsp;[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_cta h2=&#8221;Onze formules&#8221; add_button=&#8221;top&#8221; btn_title=&#8221;Maak een vrijblijvende afspraak&#8221; btn_color=&#8221;danger&#8221; btn_link=&#8221;url:http%3A%2F%2Fwww.bevershof.be%2Fnl%2Fcontact%2Ffeest-bespreken%2F||&#8221;]<\/p>\n<ul>\n<li><a title=\"Beste Bruidspaar\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/beste-bruidspaar\/\">Beste bruidspaar<\/a><\/li>\n<li><a title=\"Aperitieven\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/aperitieven\/\">Aperitieven<\/a><\/li>\n<li><a title=\"Recepties\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/recepties\/\">Recepties<\/a><\/li>\n<li><a title=\"Walking dinners\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/walking-diners\/\">Walking dinners<\/a><\/li>\n<li><a title=\"Volledig bediend aan tafel\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/volledig-bediend-aan-tafel\/\">Volledig bediend aan tafel<\/a><\/li>\n<li><a title=\"Formules dranken inbegrepen\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/formules-dranken-inbegrepen\/\">Formules dranken inbegrepen<\/a><\/li>\n<li><a title=\"Barbecue\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/barbecue\/\">Barbecue<\/a><\/li>\n<li><a title=\"Babyborrel\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/babyborrel\/\">Babyborrel<\/a><\/li>\n<li><a title=\"Brunch\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/brunch\/\">Brunch<\/a><\/li>\n<li><a title=\"Kommunie menu\u2019s\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/kommunie-menus\/\">Kommunie menu&#8217;s<\/a><\/li>\n<li><a title=\"Feestmenu\u2019s\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/feestmenus\/\">Feestmenu&#8217;s<\/a><\/li>\n<li><a title=\"Drankformules\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/drankformules\/\">Drankformules<\/a><\/li>\n<li><a title=\"Bruidstaart\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/bruidstaart\/\">Bruidstaart<\/a><\/li>\n<li><a title=\"Morgenbuffet-DJ\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/morgenbuffet-dj\/\">Morgenbuffet \/ DJ<\/a><\/li>\n<li><a title=\"Afhaalgerechten\" href=\"http:\/\/www.bevershof.be\/nl\/formules\/afhaalgerechten\/\">Afhaalgerechten<\/a><\/li>\n<\/ul>\n<h2>Zalen<\/h2>\n<ul>\n<li><a title=\"Zaal Panorama\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/zaal-panorama\/\">Panorama<\/a><\/li>\n<li><a title=\"Zaal Restaurant\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/restaurant\/\">Restaurant<\/a><\/li>\n<li><a title=\"Zaal Koepel\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/koepel\/\">Koepel<\/a><\/li>\n<li><a title=\"Zaal Spits\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/spits\/\">Spits<\/a><\/li>\n<li><a title=\"Zaal Mangerie\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/mangerie\/\">Mangerie<\/a><\/li>\n<li><a title=\"Zaal Pergola\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/pergola\/\">Pergola<\/a><\/li>\n<li><a title=\"Zaal Pyramide\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/pyramide\/\">Pyramide<\/a><\/li>\n<li><a title=\"Grote Zaal\" href=\"http:\/\/www.bevershof.be\/nl\/zalen\/grote-zaal\/\">Grote Zaal<\/a><\/li>\n<\/ul>\n<p>[\/vc_cta][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row bg_type=&#8221;no_bg&#8221;][vc_column width=&#8221;2\/3&#8243;][vc_column_text] &nbsp; &nbsp;[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_cta h2=&#8221;Onze formules&#8221; add_button=&#8221;top&#8221; btn_title=&#8221;Maak een vrijblijvende afspraak&#8221; btn_color=&#8221;danger&#8221; btn_link=&#8221;url:http%3A%2F%2Fwww.bevershof.be%2Fnl%2Fcontact%2Ffeest-bespreken%2F||&#8221;]&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":23,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-18980","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/pages\/18980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/comments?post=18980"}],"version-history":[{"count":82,"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/pages\/18980\/revisions"}],"predecessor-version":[{"id":21744,"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/pages\/18980\/revisions\/21744"}],"up":[{"embeddable":true,"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/pages\/23"}],"wp:attachment":[{"href":"https:\/\/www.bevershof.be\/nl\/wp-json\/wp\/v2\/media?parent=18980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}